{"id":17733,"date":"2025-07-01T17:49:36","date_gmt":"2025-07-01T21:49:36","guid":{"rendered":"https:\/\/appareilarchitecture.com\/client\/lab-ecole\/"},"modified":"2025-07-01T17:49:55","modified_gmt":"2025-07-01T21:49:55","slug":"lab-ecole","status":"publish","type":"client","link":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/","title":{"rendered":"Lab \u00c9cole"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-17733","client","type-client","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lab \u00c9cole - Appareil Architecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lab \u00c9cole - Appareil Architecture\" \/>\n<meta property=\"og:url\" content=\"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/\" \/>\n<meta property=\"og:site_name\" content=\"Appareil Architecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/appareilarchitecture\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T21:49:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/client\\\/lab-ecole\\\/\",\"url\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/client\\\/lab-ecole\\\/\",\"name\":\"Lab \u00c9cole - Appareil Architecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/#website\"},\"datePublished\":\"2025-07-01T21:49:36+00:00\",\"dateModified\":\"2025-07-01T21:49:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/client\\\/lab-ecole\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/client\\\/lab-ecole\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/client\\\/lab-ecole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lab \u00c9cole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/\",\"name\":\"Appareil Architecture\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/#organization\",\"name\":\"Appareil Architecture\",\"url\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/appareilarchitecture.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Appareil-architecture-logo.png\",\"contentUrl\":\"https:\\\/\\\/appareilarchitecture.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Appareil-architecture-logo.png\",\"width\":396,\"height\":68,\"caption\":\"Appareil Architecture\"},\"image\":{\"@id\":\"https:\\\/\\\/appareilarchitecture.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/appareilarchitecture\",\"https:\\\/\\\/www.instagram.com\\\/appareilarchitecture\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lab \u00c9cole - Appareil Architecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/","og_locale":"en_US","og_type":"article","og_title":"Lab \u00c9cole - Appareil Architecture","og_url":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/","og_site_name":"Appareil Architecture","article_publisher":"https:\/\/www.facebook.com\/appareilarchitecture","article_modified_time":"2025-07-01T21:49:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/","url":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/","name":"Lab \u00c9cole - Appareil Architecture","isPartOf":{"@id":"https:\/\/appareilarchitecture.com\/en\/#website"},"datePublished":"2025-07-01T21:49:36+00:00","dateModified":"2025-07-01T21:49:55+00:00","breadcrumb":{"@id":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/appareilarchitecture.com\/en\/client\/lab-ecole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/appareilarchitecture.com\/en\/"},{"@type":"ListItem","position":2,"name":"Lab \u00c9cole"}]},{"@type":"WebSite","@id":"https:\/\/appareilarchitecture.com\/en\/#website","url":"https:\/\/appareilarchitecture.com\/en\/","name":"Appareil Architecture","description":"","publisher":{"@id":"https:\/\/appareilarchitecture.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/appareilarchitecture.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/appareilarchitecture.com\/en\/#organization","name":"Appareil Architecture","url":"https:\/\/appareilarchitecture.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/appareilarchitecture.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/appareilarchitecture.com\/wp-content\/uploads\/2025\/01\/Appareil-architecture-logo.png","contentUrl":"https:\/\/appareilarchitecture.com\/wp-content\/uploads\/2025\/01\/Appareil-architecture-logo.png","width":396,"height":68,"caption":"Appareil Architecture"},"image":{"@id":"https:\/\/appareilarchitecture.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/appareilarchitecture","https:\/\/www.instagram.com\/appareilarchitecture\/"]}]}},"_links":{"self":[{"href":"https:\/\/appareilarchitecture.com\/en\/wp-json\/wp\/v2\/client\/17733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appareilarchitecture.com\/en\/wp-json\/wp\/v2\/client"}],"about":[{"href":"https:\/\/appareilarchitecture.com\/en\/wp-json\/wp\/v2\/types\/client"}],"wp:attachment":[{"href":"https:\/\/appareilarchitecture.com\/en\/wp-json\/wp\/v2\/media?parent=17733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}